{"id":1789,"date":"2024-09-25T20:53:56","date_gmt":"2024-09-26T02:53:56","guid":{"rendered":"https:\/\/pacificmarketingcr.com\/ayuda\/formulario-web-requisitos-online"},"modified":"2024-11-03T13:27:41","modified_gmt":"2024-11-03T19:27:41","slug":"formulario-web-requisitos-online","status":"publish","type":"post","link":"https:\/\/pacificmarketingcr.com\/es\/ayuda\/formulario-web-requisitos-online","title":{"rendered":"Requisitos del sitio web y formulario en l\u00ednea"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-padding-bottom-small:0px;--awb-padding-left-small:0px;--awb-margin-bottom-small:25px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2 class=\"p1\">Requisitos del sitio web<\/h2>\n<p class=\"p1\"><span class=\"s1\"><b>Informaci\u00f3n de contacto principal<br \/>\n<\/b><\/span>Necesitamos tu informaci\u00f3n de contacto o la de un miembro del equipo de la empresa, que ser\u00e1 nuestro contacto principal para tu cuenta con nosotros.<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Nombre completo.<\/li>\n<li class=\"li1\">Direcci\u00f3n de correo electr\u00f3nico actual.<\/li>\n<li class=\"li1\">N\u00famero de tel\u00e9fono.<\/li>\n<li class=\"li1\">\u00bfUtilizas WhatsApp? (S\/N).<\/li>\n<li class=\"li1\">Puesto en la empresa.<\/li>\n<\/ul>\n<p><strong>Informaci\u00f3n de la empresa<\/strong><br \/>\nEsta informaci\u00f3n se utilizar\u00e1 en el sitio web, as\u00ed que proporciona la informaci\u00f3n de contacto de la empresa.<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">Nombre de la empresa.<\/li>\n<li class=\"li1\">Eslogan (si lo hay).<\/li>\n<li class=\"li1\">Industria.<\/li>\n<li class=\"li1\">Direcci\u00f3n de correo electr\u00f3nico profesional (si la tienes).<\/li>\n<li class=\"li1\">N\u00famero(s) de tel\u00e9fono de la empresa.<\/li>\n<li class=\"li1\">Direcci\u00f3n (en su caso).<\/li>\n<li class=\"li1\">Manejadores de redes sociales (URL\/dominios).<\/li>\n<\/ul>\n<p><strong>Logotipo de empresa<\/strong><br \/>\nPor favor, facil\u00edtanos los archivos originales de tu logotipo, si no tienes los archivos originales del dise\u00f1o, facil\u00edtanos los que tengas para ver qu\u00e9 funcionar\u00e1 mejor. (PDF\/PNG\/JPG\/PSD\/AI\/EPS). Si no tienes un logotipo de empresa, podemos ayudarte a crear tu <span style=\"text-decoration: underline;\"><a href=\"https:\/\/pacificmarketingcr.com\/es\/solutions\/diseno-grafico\">logotipo de empresa<\/a><\/span> y <span style=\"text-decoration: underline;\"><a href=\"https:\/\/pacificmarketingcr.com\/es\/solutions\/diseno-grafico\">gr\u00e1ficos<\/a><\/span>.<\/p>\n<p><strong>Dominio del sitio web<br \/>\n<\/strong>Si ya tienes un dominio, por favor, h\u00e1znoslo saber para que podamos apuntar el dominio al servidor adecuado (si es necesario). Si no tienes un dominio buscaremos el nombre de tu empresa como opci\u00f3n, tambi\u00e9n buscaremos la mejor opci\u00f3n para <span style=\"text-decoration: underline;\"><a href=\"https:\/\/pacificmarketingcr.com\/es\/solutions\/web-seo\">SEO<\/a><\/span> y te la proporcionaremos para que elijas.<\/p>\n<p><strong>Contenido para el sitio web<\/strong><br \/>\n\u00c9sta es la informaci\u00f3n que no podemos crear para ti, la informaci\u00f3n vital sobre tus productos, servicios y negocio. Siempre podemos a\u00f1adir m\u00e1s informaci\u00f3n m\u00e1s adelante, pero cuanto antes nos facilites la informaci\u00f3n necesaria, antes podremos avanzar en la creaci\u00f3n de tu sitio web.<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>Introducci\u00f3n sobre ti\/empresa <\/b>(\u00bfQui\u00e9n eres? \u00bfPor qu\u00e9 hacer negocios contigo? \u00bfEn qu\u00e9 te diferencias del resto?).<\/li>\n<li class=\"li1\"><b>Sobre nosotros\/declaraci\u00f3n de misi\u00f3n <\/b>(h\u00e1blanos de ti\/de tu empresa, \u00bfcu\u00e1l es tu historia?).<\/li>\n<li class=\"li1\"><b>Productos\/servicios<\/b> (informaci\u00f3n sobre lo que ofreces, descripciones de productos, servicios, precios, etc.).<\/li>\n<li class=\"li1\">Esl\u00f3ganes, citas, cualquier informaci\u00f3n adicional que pueda hacer que tu cliente elija tus productos\/servicios.<\/li>\n<li class=\"li1\"><b>Contacto<\/b> (horario comercial, direcciones, informaci\u00f3n para ponerse en contacto contigo, etc.)<\/li>\n<\/ul>\n<p class=\"p1\"><strong>Dise\u00f1o<\/strong><br \/>\n\u00bfTienes una paleta de colores que te gustar\u00eda utilizar? Si no es as\u00ed, solemos basarnos en los colores de tu logotipo. Asimismo, si tienes alg\u00fan tipo de letra que te gustar\u00eda utilizar, facil\u00edtanos esta informaci\u00f3n. Si est\u00e1s abierto a nuestras sugerencias, crearemos un archivo maestro para que puedas seguir utiliz\u00e1ndolas con tu marca.<\/p>\n<p><strong>Im\u00e1genes<\/strong><br \/>\nTomadas profesionalmente <span style=\"text-decoration: underline;\"><a href=\"https:\/\/pacificmarketingcr.com\/es\/solutions\/fotografia\">fotos de tu negocio<\/a><\/span>\u00a0productos, personal, etc. ser\u00e1n siempre nuestra recomendaci\u00f3n, potenciar\u00e1n tu imagen y nos proporcionar\u00e1n las im\u00e1genes de alta definici\u00f3n que necesitamos. Podemos prestar este servicio (a clientes en Costa Rica). Si no tienes im\u00e1genes profesionales, podemos conformarnos con las que tengas, te pedimos las im\u00e1genes de mejor calidad que puedas tener, siempre tomadas en horizontal para permitirnos un mejor aprovechamiento de tus fotos. Podemos aceptarlas por Google Drive, Dropbox, WeTransfer o WhatsApp con HD activado.<\/p>\n<p><strong>\u00a1Empecemos!<br \/>\n<\/strong>Ahora podemos empezar a estructurar tu sitio web. Primero recopilaremos la informaci\u00f3n que nos proporciones, crearemos tu perfil y empezaremos a estructurar el dise\u00f1o de tu sitio web. A continuaci\u00f3n, empezaremos a a\u00f1adir contenido para trazar el dise\u00f1o y ponerlo en marcha. Una vez que hayamos resuelto los detalles, te daremos acceso para que lo veas en directo, \u00a1una vez que confirmes el dise\u00f1o lo indexamos para que el mundo lo disfrute!<\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" title=\"Rellena y env\u00eda el formulario de requisitos en l\u00ednea para sitios web.\" aria-label=\"Rellena y env\u00eda el formulario de requisitos en l\u00ednea para sitios web.\" href=\"https:\/\/pacificmarketingcr.com\/es\/ayuda\/formularios\/primeros-pasos\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Completa el formulario en l\u00ednea<\/span><i class=\"fa-file-alt fas awb-button__icon awb-button__icon--default button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Necesitamos tu informaci\u00f3n de contacto o la de un miembro del equipo de la empresa, que ser\u00e1 nuestro contacto principal para tu cuenta con nosotros&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[68],"class_list":["post-1789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuda","tag-requisitos"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/posts\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":0,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/media\/1481"}],"wp:attachment":[{"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pacificmarketingcr.com\/es\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}